{"id":2812,"date":"2022-01-29T02:05:00","date_gmt":"2022-01-29T02:05:00","guid":{"rendered":"http:\/\/grupoaduan.com\/?page_id=2812"},"modified":"2026-02-04T18:51:59","modified_gmt":"2026-02-04T18:51:59","slug":"n","status":"publish","type":"page","link":"https:\/\/grupoaduan.com\/en\/n\/","title":{"rendered":"Us"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2812\" class=\"elementor elementor-2812\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5abf641c elementor-section-boxed elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"5abf641c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cef7c53 lakit-col-width-auto-no\" data-id=\"3cef7c53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e540e6b elementor-widget elementor-widget-heading\" data-id=\"5e540e6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7803a9c7 elementor-widget__width-auto elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"7803a9c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/grupoaduan.com\/en\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tinicio<i class=\"fas fa-chevron-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1864f8c4 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"1864f8c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Us<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fef0b9d elementor-section-boxed elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"2fef0b9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4d04e6e3 lakit-col-width-auto-no\" data-id=\"4d04e6e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f55e25f elementor-widget elementor-widget-elementskit-heading\" data-id=\"2f55e25f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider elementskit-style-long\"><div class=\"elementskit-border-divider elementskit-style-long\"><\/div><\/div><h2 class=\"ekit-heading--title elementskit-section-title\">Us<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c08baa1 elementor-widget elementor-widget-heading\" data-id=\"5c08baa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">GRUPO ADUAN <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b507bf elementor-widget elementor-widget-text-editor\" data-id=\"73b507bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>GRUPO ADUAN<\/strong>\u00a0esta conformado por\u00a0<strong>GRUPO ADUAN-OPERADOR LOGISTICO<\/strong>\u00a0y\u00a0<strong>GRUPO ADUAN-AGENCIA DE ADUANA<\/strong>.<\/p><p>Somos un grupo humano con gran experiencia en el campo del comercio exterior, y altamente calificado que nos permite brindar un servicio de calidad, eficaz, y seguro al momento de elegir nuestros servicios.<\/p><p>Nuestro personal cuenta con capacitaciones permanentes, utilizando tecnolog\u00eda de punta y sistemas inform\u00e1ticos e integrados, creados y desarrollados pensando en la necesidad de nuestros asociados en negocios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-59c17f2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59c17f2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-115b0c64 lakit-col-width-auto-no\" data-id=\"115b0c64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33e444c4 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"33e444c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-stats-4\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46c5d2ab elementor-widget__width-auto elementor-widget elementor-widget-counter\" data-id=\"46c5d2ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">A\u00f1os de Experiencia<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"15\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37981975 lakit-col-width-auto-no\" data-id=\"37981975\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60c4474d elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"60c4474d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checkmark-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-335832e0 elementor-widget__width-auto elementor-widget elementor-widget-counter\" data-id=\"335832e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Alianzas en diferentes Pa\u00edses<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"89\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ec5635 lakit-col-width-auto-no\" data-id=\"ec5635\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38d347bc elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"38d347bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/grupoaduan.com\/en\/agencia-de-carga\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1023\" height=\"1022\" src=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/ship_1@2x.png\" class=\"attachment-full size-full wp-image-2658\" alt=\"\" srcset=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/ship_1@2x.png 1023w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/ship_1@2x-300x300.png 300w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/ship_1@2x-150x150.png 150w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/ship_1@2x-768x767.png 768w\" sizes=\"(max-width: 1023px) 100vw, 1023px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/grupoaduan.com\/en\/agencia-de-carga\/\">GRUPO ADUAN OPERADOR LOG\u00cdSTICO <\/a><\/h3><p class=\"elementor-image-box-description\">Es miembro afiliado a la Camara de Comercio de Lima y de la WCA (95109), brindando a nuestros asociados en negocios la seguridad que la log\u00edstica del transporte internacional necesita, a trav\u00e9s de una red de agentes altamente competitivos y con el menor riesgo posible.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13e18a05 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"13e18a05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/grupoaduan.com\/en\/agencia-de-aduanas\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"1022\" height=\"1022\" src=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/aeroplane_1@2x.png\" class=\"attachment-full size-full wp-image-2659\" alt=\"\" srcset=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/aeroplane_1@2x.png 1022w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/aeroplane_1@2x-300x300.png 300w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/aeroplane_1@2x-150x150.png 150w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2022\/01\/aeroplane_1@2x-768x768.png 768w\" sizes=\"(max-width: 1022px) 100vw, 1022px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h1 class=\"elementor-image-box-title\"><a href=\"https:\/\/grupoaduan.com\/en\/agencia-de-aduanas\/\">GRUPO ADUAN \u2013 AGENCIA DE ADUANA <\/a><\/h1><p class=\"elementor-image-box-description\">Nuestro \u00e9xito en las operaciones de comercio exterior, se basa en el grupo humano que forma la familia de GRUPO ADUAN. Todas las actividades que desarrolla nuestro personal, lo hace con un alto grado de eficacia, puntualidad y responsabilidad, las cuales son la clave de nuestro Exito.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ea07d25 elementor-section-boxed elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"6ea07d25\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3be7d2d8 lakit-col-width-auto-no\" data-id=\"3be7d2d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f03c0e8 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"1f03c0e8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-20e9b03f lakit-col-width-auto-no\" data-id=\"20e9b03f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ac6d635 jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"2ac6d635\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position- elementor-animation- jeg_module___6a983f23e4a41\" ><div class=\"jkit-icon-box-wrapper hover-from-bottom\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><i aria-hidden=\"true\" class=\"jki jki-Consultancy-light\"><\/i><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h3 class=\"title\">Visi\u00f3n<\/h3><p class=\"icon-box-description\">Ser el principal operador log\u00edstico y agencia de aduana de Latinoam\u00e9rica, ser el mejor referente de buena calidad y servicio para otros operadores de comercio del mundo.<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-edfdfe2 lakit-col-width-auto-no\" data-id=\"edfdfe2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-326a073 jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"326a073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position- elementor-animation- jeg_module__1_6a983f23e66af\" ><div class=\"jkit-icon-box-wrapper hover-from-bottom\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><i aria-hidden=\"true\" class=\"jki jki-target-2-light\"><\/i><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h3 class=\"title\">Misi\u00f3n<\/h3><p class=\"icon-box-description\">Ser el principal socio estrat\u00e9gico de la peque\u00f1a, mediana y grande empresa en su cadena log\u00edstica. Buscar soluciones a sus problemas y asesorar a nuestros socios comerciales en la toma de decisiones de manera eficiente y con alto sentido de conocimiento.<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-02405b7 lakit-col-width-auto-no\" data-id=\"02405b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-542d19b jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"542d19b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position- elementor-animation- jeg_module__2_6a983f23e7be7\" ><div class=\"jkit-icon-box-wrapper hover-from-bottom\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><i aria-hidden=\"true\" class=\"jki jki-target-2-light\"><\/i><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h3 class=\"title\">Valores<\/h3><p class=\"icon-box-description\">\u2022\tResponsabilidad\n\u2022\tHonestidad\n\u2022\tOrden\n\u2022\tSinceridad\n\u2022\tVocaci\u00f3n de Trabajo\n<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab9e60d elementor-section-boxed elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"ab9e60d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d331fd lakit-col-width-auto-no\" data-id=\"7d331fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e457a44 elementor-widget elementor-widget-heading\" data-id=\"e457a44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra Pol\u00edtica SIG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-65bbfc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65bbfc1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cd83ce7 lakit-col-width-auto-no\" data-id=\"cd83ce7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca61ab0 elementor-widget elementor-widget-accordion\" data-id=\"ca61ab0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2121\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2121\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">GRUPO ADUAN<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2121\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2121\"><p>GRUPO ADUAN, est\u00e1 conformado por GRUPO ADUAN AGENCIA DE ADUANA S.A.C., quien brinda servicio de agenciamiento aduanero y GRUPO ADUAN OPERADOR LOG\u00cdSTICO S.A.C., quien brinda servicios como agente de carga internacional, transporte terrestre local, cuadrilla, custodia tanto para los servicios de importaci\u00f3n como de exportaci\u00f3n en todas sus modalidades.\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2122\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2122\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Nuestro compromiso<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2122\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2122\"><p>Nuestro compromiso es gestionar procesos de manera eficaz y segura bajo el cumplimiento de los acuerdos con nuestros clientes, normativas legales vigentes y aquellas adoptadas por la organizaci\u00f3n, con el \u00fanico prop\u00f3sito de lograr la mejora continua del SIG, para lo cual:<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1bfe968 lakit-col-width-auto-no\" data-id=\"1bfe968\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc6f8ad elementor-widget elementor-widget-accordion\" data-id=\"cc6f8ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2141\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2141\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Contamos con colaboradores:<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2141\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2141\"><ul><li>Calificados, capacitados, concientizados en sus procesos, SIG y con vocaci\u00f3n de servicio al cliente.<\/li><li>Comprometidos y con responsabilidades definidas.<\/li><li>Contamos con los recursos necesarios para satisfacer las necesidades y expectativas de nuestros clientes y partes interesadas.<\/li><li>Prevenimos o reducimos riesgos sobre:<\/li><li>Actividades il\u00edcitas, como TID, LAFT, contrabando, robo, corrupci\u00f3n y soborno, as\u00ed como todo riesgo que afecte la seguridad cadena log\u00edstica del comercio internacional.<\/li><li>Aspectos que afecten la calidad del servicio y\/o satisfacci\u00f3n del Cliente<\/li><li>Los peligros que afecten a los trabajadores y grupos de inter\u00e9s en las actividades que efectuamos en el servicio como agenciamiento aduanero o en el servicio como operador log\u00edstico.\u00a0<\/li><li>Proporcionamos condiciones de trabajo seguras y saludables para la prevenci\u00f3n de ocurrencia de accidentes y enfermedades ocupacionales de nuestros colaboradores y de los grupos de inter\u00e9s en las actividades que realizamos.<\/li><li>Promovemos una participaci\u00f3n activa y de consulta con nuestros colaboradores en la prevenci\u00f3n lesiones, dolencias, enfermedades e incidentes o accidentes relacionados con el trabajo.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2142\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2142\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Nuestra Pol\u00edtica SIG<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2142\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2142\"><p>Nuestra Pol\u00edtica SIG proporciona un marco de referencia para establecer y revisar los Objetivos del SIG y ser\u00e1 revisada por la Alta Gerencia con una periodicidad anual o cuando exista cambios en el marco comercial del GRUPO ADUAN que pueda afectar la existencia continua o la relevancia del SIG, para asegurarse que siempre sea adecuada a las necesidades y compatible con el Sistema Integrado de Gesti\u00f3n. Nuestra Pol\u00edtica SIG es difundida y comunicada a todas las partes interesadas y\/o interesados en conocerla.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-722f105 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"722f105\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-98fef48 lakit-col-width-auto-no\" data-id=\"98fef48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-442b2dc elementor-widget elementor-widget-heading\" data-id=\"442b2dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descargar Politicas SIG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-491d7a4 lakit-col-width-auto-no\" data-id=\"491d7a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a3ccaa elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5a3ccaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2026\/02\/GAC-SIG-GE-02-POLITICA-DEL-SIG-para-la-WEB-2026-1.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descargar PDF<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bd702eb elementor-section-boxed elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"3bd702eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d211a48 lakit-col-width-auto-no\" data-id=\"5d211a48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31179b70 elementor-widget elementor-widget-elementskit-heading\" data-id=\"31179b70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider elementskit-style-long\"><div class=\"elementskit-border-divider elementskit-style-long\"><\/div><\/div><h2 class=\"ekit-heading--title elementskit-section-title\">Expert Team<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70db2816 elementor-widget elementor-widget-heading\" data-id=\"70db2816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros Expertos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-68b15cbe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68b15cbe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a93603a lakit-col-width-auto-no\" data-id=\"a93603a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1368810c elementor-widget__width-initial elementor-widget elementor-widget-elementskit-team\" data-id=\"1368810c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"profile-image-card elementor-animation- ekit-team-img ekit-team-style-overlay text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-ruth.jpg\" class=\"attachment-full size-full wp-image-3296\" alt=\"\" srcset=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-ruth.jpg 1000w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-ruth-300x300.jpg 300w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-ruth-150x150.jpg 150w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-ruth-768x768.jpg 768w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-ruth-12x12.jpg 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hover-area\">\n\t\t\t\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"profile-designation\"><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"profile-footer\">\n\t\t\t\t\t\t\t\t\t<ul class=\"ekit-team-social-list\">\n\t\t\t<li class=\"elementor-repeater-item-c836328\">\n\t\t\t<a href=\"#\" aria-label=\"Facebook\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-facebook\"><\/i>\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t<li class=\"elementor-repeater-item-1cee149\">\n\t\t\t<a href=\"#\" aria-label=\"Twitter\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t<li class=\"elementor-repeater-item-dc32a6d\">\n\t\t\t<a href=\"#\" aria-label=\"Twitter\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-linkedin\"><\/i>\t\t\t<\/a>\n\t\t<\/li>\n\t<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-592bfe23 eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"592bfe23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h2 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Ruth Alvarez<\/span> <span class=\"eael-dch-title-text\"><\/span><\/h2>\t\t\t\t\t<span class=\"subtext\"><p>Representante Aduanero<\/p><\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-17fe17c1 lakit-col-width-auto-no\" data-id=\"17fe17c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-681ea836 elementor-widget__width-initial elementor-widget elementor-widget-elementskit-team\" data-id=\"681ea836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"profile-image-card elementor-animation- ekit-team-img ekit-team-style-overlay text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-alberto.jpg\" class=\"attachment-full size-full wp-image-3295\" alt=\"\" srcset=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-alberto.jpg 1000w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-alberto-300x300.jpg 300w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-alberto-150x150.jpg 150w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-alberto-768x768.jpg 768w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/sr-alberto-12x12.jpg 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hover-area\">\n\t\t\t\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"profile-designation\"><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"profile-footer\">\n\t\t\t\t\t\t\t\t\t<ul class=\"ekit-team-social-list\">\n\t\t\t<li class=\"elementor-repeater-item-c836328\">\n\t\t\t<a href=\"#\" aria-label=\"Facebook\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-facebook\"><\/i>\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t<li class=\"elementor-repeater-item-1cee149\">\n\t\t\t<a href=\"#\" aria-label=\"Twitter\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t<li class=\"elementor-repeater-item-3a39e0a\">\n\t\t\t<a href=\"#\" aria-label=\"Linkedin\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-linkedin\"><\/i>\t\t\t<\/a>\n\t\t<\/li>\n\t<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2238e257 eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"2238e257\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h2 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Alberto Chacon<\/span> <span class=\"eael-dch-title-text\"><\/span><\/h2>\t\t\t\t\t<span class=\"subtext\"><p>Gerente General<\/p><\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-123f5c37 lakit-col-width-auto-no\" data-id=\"123f5c37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-686374f7 elementor-widget__width-initial elementor-widget elementor-widget-elementskit-team\" data-id=\"686374f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"profile-image-card elementor-animation- ekit-team-img ekit-team-style-overlay text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/FOTO-COORPORATIVA-scaled.jpg\" class=\"attachment-full size-full wp-image-3293\" alt=\"\" srcset=\"https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/FOTO-COORPORATIVA-scaled.jpg 2560w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/FOTO-COORPORATIVA-300x300.jpg 300w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/FOTO-COORPORATIVA-1024x1024.jpg 1024w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/FOTO-COORPORATIVA-150x150.jpg 150w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/FOTO-COORPORATIVA-768x768.jpg 768w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/FOTO-COORPORATIVA-1536x1536.jpg 1536w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/FOTO-COORPORATIVA-2048x2048.jpg 2048w, https:\/\/grupoaduan.com\/wp-content\/uploads\/2024\/12\/FOTO-COORPORATIVA-12x12.jpg 12w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hover-area\">\n\t\t\t\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"profile-designation\"><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"profile-footer\">\n\t\t\t\t\t\t\t\t\t<ul class=\"ekit-team-social-list\">\n\t\t\t<li class=\"elementor-repeater-item-c836328\">\n\t\t\t<a href=\"#\" aria-label=\"Facebook\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-facebook\"><\/i>\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t<li class=\"elementor-repeater-item-1cee149\">\n\t\t\t<a href=\"#\" aria-label=\"Twitter\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t<\/a>\n\t\t<\/li>\n\t\t\t<li class=\"elementor-repeater-item-3a39e0a\">\n\t\t\t<a href=\"#\" aria-label=\"Linkedin\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-linkedin\"><\/i>\t\t\t<\/a>\n\t\t<\/li>\n\t<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-791d4af2 eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"791d4af2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h2 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Julisa Zeballos <\/span> <span class=\"eael-dch-title-text\"><\/span><\/h2>\t\t\t\t\t<span class=\"subtext\"><p>Gerente Comercial<\/p><\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nosotros inicio Nosotros Nosotros GRUPO ADUAN GRUPO ADUAN\u00a0esta conformado por\u00a0GRUPO ADUAN-OPERADOR LOGISTICO\u00a0y\u00a0GRUPO ADUAN-AGENCIA DE ADUANA. Somos un grupo humano con gran experiencia en el campo del comercio exterior, y altamente calificado que nos permite brindar un servicio de calidad, eficaz, y seguro al momento de elegir nuestros servicios. Nuestro personal cuenta con capacitaciones permanentes, utilizando [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"class_list":["post-2812","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/grupoaduan.com\/en\/wp-json\/wp\/v2\/pages\/2812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupoaduan.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/grupoaduan.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/grupoaduan.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grupoaduan.com\/en\/wp-json\/wp\/v2\/comments?post=2812"}],"version-history":[{"count":5,"href":"https:\/\/grupoaduan.com\/en\/wp-json\/wp\/v2\/pages\/2812\/revisions"}],"predecessor-version":[{"id":3336,"href":"https:\/\/grupoaduan.com\/en\/wp-json\/wp\/v2\/pages\/2812\/revisions\/3336"}],"wp:attachment":[{"href":"https:\/\/grupoaduan.com\/en\/wp-json\/wp\/v2\/media?parent=2812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}